{"id":2725,"date":"2022-04-10T10:05:48","date_gmt":"2022-04-10T10:05:48","guid":{"rendered":"https:\/\/entangelments.de\/engel-der-auferstehung-i-angel-of-the-resurrection"},"modified":"2022-11-07T09:12:36","modified_gmt":"2022-11-07T09:12:36","slug":"engel-der-auferstehung-i-angel-of-the-resurrection","status":"publish","type":"post","link":"https:\/\/entangelments.de\/es\/engel-der-auferstehung-i-angel-of-the-resurrection","title":{"rendered":"\u00c1ngel de la resurreci\u00f3n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Ver es creer<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_engel_bunt.jpg\" alt=\"\" class=\"wp-image-1410\" srcset=\"https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_engel_bunt.jpg 1920w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_engel_bunt-384x216.jpg 384w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_engel_bunt-192x108.jpg 192w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_engel_bunt-768x432.jpg 768w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_engel_bunt-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><figcaption class=\"wp-element-caption\">Engel der Auferstehung, Heiliges Grab, Heiliges Grab, <a href=\"https:\/\/www.kunstsammlungen-chemnitz.de\/haeuser\/schlossbergmuseum\/\" data-type=\"URL\" data-id=\"https:\/\/www.kunstsammlungen-chemnitz.de\/haeuser\/schlossbergmuseum\/\">Kunstsammlungen Chemnitz, Schlo\u00dfbergmuseum<\/a>. Fotograf: Mirko, Lizenz <a href=\"https:\/\/creativecommons.org\/publicdomain\/mark\/1.0\/deed.de\" data-type=\"URL\" data-id=\"https:\/\/creativecommons.org\/publicdomain\/mark\/1.0\/deed.de\">Public domain<\/a>, via Wikimedia Commons<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En la Edad Media, ver significaba creer, es la conclusi\u00f3n de Uwe Fiedler del v\u00eddeo en el que describe el Santo Sepulcro, cedido al cuidado del Schlo\u00dfbergmuseum de Chemnitz, como un teatro de marionetas de la historia b\u00edblica de la Pascua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Santo Sepulcro de la Jakobikirche de Chemnitz, creado entre 1480 y 1520, vuelve a estar en el Schlo\u00dfbergmuseum desde octubre de 2001, tras una exhaustiva restauraci\u00f3n. La escenograf\u00eda del g\u00f3tico tard\u00edo, realizada en madera de tilo, sigue el modelo de una catedral g\u00f3tica sin canciller\u00eda. La Pasi\u00f3n de Cristo (historia de la Pasi\u00f3n y la Pascua) se representa en dos niveles del magn\u00edfico santuario transportable. El pedestal sirve para sostener el cuerpo de Jes\u00fas bajado de la cruz.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_waechter.jpg\" alt=\"\" class=\"wp-image-1416\" srcset=\"https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_waechter.jpg 1920w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_waechter-384x216.jpg 384w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_waechter-192x108.jpg 192w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_waechter-768x432.jpg 768w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_waechter-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><figcaption class=\"wp-element-caption\">W\u00e4chter, Heiliges Grab,<a href=\"https:\/\/www.kunstsammlungen-chemnitz.de\/haeuser\/schlossbergmuseum\/\" data-type=\"URL\" data-id=\"https:\/\/www.kunstsammlungen-chemnitz.de\/haeuser\/schlossbergmuseum\/\"> Kunstsammlungen Chemnitz,<br>Schlo\u00dfbergmuseum<\/a>.  Fotograf: Mirko, Lizenz <a href=\"https:\/\/creativecommons.org\/publicdomain\/mark\/1.0\/deed.de\" data-type=\"URL\" data-id=\"https:\/\/creativecommons.org\/publicdomain\/mark\/1.0\/deed.de\">Public domain<\/a>, via Wikimedia Commons<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En el nivel del pedestal, los guardias encargados por Poncio Pilato se agazapan y mienten para impedir que se cumpla la antigua profec\u00eda b\u00edblica, seg\u00fan la cual uno resucita de entre los muertos y se levanta de la tumba.<br>\u00abPorque no me abandonar\u00e1s a la muerte, ni admitir\u00e1s que tu Santo vea la fosa. Me das a conocer el camino de la vida: En tu presencia hay plenitud de gozo, y deleite a tu diestra para siempre\u00bb. (Salmo 16:10-11)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los guardias parecen somnolientos, todos se protegen los ojos con las viseras de sus cascos y\/o se apartan de la acci\u00f3n. Pero uno de los guardias levanta la cabeza, vuelve los ojos hacia arriba y los protege con la mano derecha, \u00bfcontra qu\u00e9? S\u00f3lo puede ser una luz brillante a la que mira al despertar, pues el Nuevo Testamento no informa de ning\u00fan testigo de la resurrecci\u00f3n, salvo en el Evangelio ap\u00f3crifo de Pedro. El Evangelio de Mateo, sin embargo, habla de un \u00e1ngel cuyo<br>\u00ab(\u2026) su forma era como un rayo, y su vestimenta blanca como la nieve. Pero los guardias se aterrorizaron de \u00e9l y quedaron como muertos\u00bb. (Mateo 28:3-4)<br>La aparici\u00f3n del \u00e1ngel hace que los guardias se congelen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_karfreitagsseite_bunt-2.jpg\" alt=\"\" class=\"wp-image-1422\" srcset=\"https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_karfreitagsseite_bunt-2.jpg 1920w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_karfreitagsseite_bunt-2-384x216.jpg 384w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_karfreitagsseite_bunt-2-192x108.jpg 192w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_karfreitagsseite_bunt-2-768x432.jpg 768w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_karfreitagsseite_bunt-2-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><figcaption class=\"wp-element-caption\">Mutter Maria, Heiliges Grab, <a href=\"https:\/\/www.kunstsammlungen-chemnitz.de\/haeuser\/schlossbergmuseum\/\" data-type=\"URL\" data-id=\"https:\/\/www.kunstsammlungen-chemnitz.de\/haeuser\/schlossbergmuseum\/\">Kunstsammlungen Chemnitz,<br>Schlo\u00dfbergmuseum<\/a>.  Fotograf: Mirko, Lizenz <a href=\"https:\/\/creativecommons.org\/publicdomain\/mark\/1.0\/deed.de\" data-type=\"URL\" data-id=\"https:\/\/creativecommons.org\/publicdomain\/mark\/1.0\/deed.de\">Public domain<\/a>, via Wikimedia Commons<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En el segundo nivel del santuario estatal hay esculturas completas en consolas.<br>En el \u00abbando del Viernes Santo\u00bb est\u00e1 Jos\u00e9 de Arimatea, que pide permiso a Poncio Pilato para enterrar el cuerpo de Jes\u00fas. La madre Mar\u00eda y probablemente Mar\u00eda Klopa (tambi\u00e9n Mar\u00eda Cleof\u00e1s\/Kleofa) tambi\u00e9n se encuentran aqu\u00ed, lament\u00e1ndose como si todav\u00eda estuvieran junto a la cruz:<br>\u00abEstaban junto a la cruz de Jes\u00fas su madre y la hermana de su madre, Mar\u00eda la mujer de Clopa, y Mar\u00eda de Magdala\u00bb. (Juan 19:25)<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_nikodemus_bunt.jpg\" alt=\"\" class=\"wp-image-1414\" srcset=\"https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_nikodemus_bunt.jpg 1920w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_nikodemus_bunt-384x216.jpg 384w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_nikodemus_bunt-192x108.jpg 192w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_nikodemus_bunt-768x432.jpg 768w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_nikodemus_bunt-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><figcaption class=\"wp-element-caption\">Nikodemus, Heiliges Grab, <a href=\"https:\/\/www.kunstsammlungen-chemnitz.de\/haeuser\/schlossbergmuseum\/\" data-type=\"URL\" data-id=\"https:\/\/www.kunstsammlungen-chemnitz.de\/haeuser\/schlossbergmuseum\/\">Kunstsammlungen Chemnitz,<br>Schlo\u00dfbergmuseum<\/a>. Fotograf: Mirko, Lizenz <a href=\"https:\/\/creativecommons.org\/publicdomain\/mark\/1.0\/deed.de\" data-type=\"URL\" data-id=\"https:\/\/creativecommons.org\/publicdomain\/mark\/1.0\/deed.de\">Public domain<\/a>, via Wikimedia Commons<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En el lado estrecho que pertenece al lado del Viernes Santo, Nicodemo est\u00e1 de pie y presenta los instrumentos del suplicio de Cristo, la corona de espinas y los tres clavos, con un gesto de sus dos manos extendidas hacia adelante y abiertas. La mano izquierda de Nicodemo y las herramientas han desaparecido hoy. En su v\u00eddeo, el director del Museo Schlossberg, Uwe Fiedler, transmite este gesto de forma muy v\u00edvida.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_osterseite_bunt-2.jpg\" alt=\"\" class=\"wp-image-1423\" srcset=\"https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_osterseite_bunt-2.jpg 1920w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_osterseite_bunt-2-384x216.jpg 384w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_osterseite_bunt-2-192x108.jpg 192w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_osterseite_bunt-2-768x432.jpg 768w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_osterseite_bunt-2-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><figcaption class=\"wp-element-caption\">Maria Magdala, Heiliges Grab, <a href=\"https:\/\/www.kunstsammlungen-chemnitz.de\/haeuser\/schlossbergmuseum\/\" data-type=\"URL\" data-id=\"https:\/\/www.kunstsammlungen-chemnitz.de\/haeuser\/schlossbergmuseum\/\">Kunstsammlungen Chemnitz,<br>Schlo\u00dfbergmuseum<\/a>. Fotograf: Mirko, Lizenz <a href=\"https:\/\/creativecommons.org\/publicdomain\/mark\/1.0\/deed.de\" data-type=\"URL\" data-id=\"https:\/\/creativecommons.org\/publicdomain\/mark\/1.0\/deed.de\">Public domain<\/a>, via Wikimedia Commons<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda Magdalena (Mar\u00eda de Magdala) aparece en la p\u00e1gina de Pascua, radiante de alegr\u00eda por la resurrecci\u00f3n de Jes\u00fas, al igual que los disc\u00edpulos de Jes\u00fas, Pedro y Juan Evangelista.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_engel_bunt.jpg\" alt=\"\" class=\"wp-image-1410\" srcset=\"https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_engel_bunt.jpg 1920w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_engel_bunt-384x216.jpg 384w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_engel_bunt-192x108.jpg 192w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_engel_bunt-768x432.jpg 768w, https:\/\/entangelments.de\/wp-content\/uploads\/2022\/03\/heiliges-grab_engel_bunt-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><figcaption class=\"wp-element-caption\">Engel der Auferstehung, Heiliges Grab, <a href=\"https:\/\/www.kunstsammlungen-chemnitz.de\/haeuser\/schlossbergmuseum\/\" data-type=\"URL\" data-id=\"https:\/\/www.kunstsammlungen-chemnitz.de\/haeuser\/schlossbergmuseum\/\">Kunstsammlungen Chemnitz,<br>Schlo\u00dfbergmuseum<\/a>.  Fotograf: Mirko, Lizenz <a href=\"https:\/\/creativecommons.org\/publicdomain\/mark\/1.0\/deed.de\" data-type=\"URL\" data-id=\"https:\/\/creativecommons.org\/publicdomain\/mark\/1.0\/deed.de\">Public domain<\/a>, via Wikimedia Commons<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En el segundo lado estrecho, un \u00e1ngel sin alas se encuentra sobre su consola. Sobre su brazo izquierdo ha colocado los sudarios de Jes\u00fas, su mano derecha est\u00e1 sobre ellos como si los protegiera. Este es el \u00e1ngel de la resurrecci\u00f3n de pie en el \u00ablado de la Pascua\u00bb de la santa tumba. Lleva la mortaja vac\u00eda y as\u00ed significa: La tumba est\u00e1 vac\u00eda: Jes\u00fas ha resucitado.<br>El \u00ab\u00c1ngel del Se\u00f1or\u00bb s\u00f3lo aparece en carne y hueso en este punto del Evangelio de Mateo; por lo dem\u00e1s, los \u00e1ngeles proclaman sus mensajes en sue\u00f1os. Mateo lo viste con un manto blanco: \u00ab(\u2026) su manto blanco como la nieve\u00bb (Mat 28,3) y as\u00ed lo distingue claramente como una figura celestial perteneciente a Dios, enviada por Dios que act\u00faa a trav\u00e9s de ellos.<br>El \u00c1ngel de la Resurrecci\u00f3n de Chemnitz lleva una t\u00fanica de oro, siguiendo la l\u00ednea de Lucas 24:4, que reviste a sus mensajeros celestiales con \u00abt\u00fanicas brillantes\u00bb.<br>envoltorios. Nadie es testigo de la resurrecci\u00f3n, pues s\u00f3lo el \u00e1ngel hace rodar la piedra antes de la apertura del sepulcro. Por eso aparece despu\u00e9s de la resurrecci\u00f3n de Jes\u00fas y muestra a las mujeres la tumba vac\u00eda, que Jes\u00fas ya ha dejado. Juan tambi\u00e9n atribuye a Jes\u00fas resucitado la cualidad de poder pasar a trav\u00e9s de puertas cerradas, de muros:<br>\u00abDespu\u00e9s de ocho d\u00edas, sus disc\u00edpulos se reunieron de nuevo dentro, y Tom\u00e1s estaba con ellos. Cuando se cerraron las puertas, vino Jes\u00fas, se puso en medio de ellos y dijo: \u00abPaz a vosotros\u00bb. (Jn 20:26)<br>El \u00e1ngel es el garante de la resurrecci\u00f3n y por eso muestra el sudario vac\u00edo como confirmaci\u00f3n. Ver es creer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No es gratuito que el manto del \u00e1ngel de la resurrecci\u00f3n sea blanco (o brillante, dorado), ya que esto establece una analog\u00eda inversa entre \u00e9l y Jes\u00fas.<br>Durante la transformaci\u00f3n de Jes\u00fas, su rostro y su ropa cambian:<br>\u00abY se transform\u00f3 ante ellos, y su rostro brill\u00f3 como el sol, y sus vestidos se volvieron blancos como la luz\u00bb. (Mt 17:1-9)<br>En Mt 28 se describe el rostro brillante y el manto blanco del \u00e1ngel de la resurrecci\u00f3n en la misma secuencia en la que tiene lugar la transfiguraci\u00f3n de Jes\u00fas.<br>Inmediatamente despu\u00e9s siguen los pasajes que hablan de la pr\u00f3xima resurrecci\u00f3n de Jes\u00fas:<br>\u00abY cuando bajaron del monte, Jes\u00fas les orden\u00f3, diciendo: No hablar\u00e1s a nadie de esta aparici\u00f3n hasta que el Hijo del Hombre haya resucitado\u00bb. (Mat 17:9).<br>La Transfiguraci\u00f3n transforma a Jes\u00fas, el Hijo del Hombre, en el Hijo de Dios por medio de su mismo Padre:<br>\u00abMientras a\u00fan hablaba as\u00ed, he aqu\u00ed que una ligera nube los cubri\u00f3. Y he aqu\u00ed una voz desde la nube que dec\u00eda: Este es mi Hijo amado, en quien me complazco; a \u00e9l oir\u00e9is\u00bb. (Mt 17,5).<br>Anticipa su posterior resurrecci\u00f3n y ya insin\u00faa que su cuerpo astral puede atravesar las paredes. La semejanza del \u00e1ngel de la resurrecci\u00f3n con el Jes\u00fas transformado es, pues, intencionada, el \u00e1ngel una referencia retrospectiva a Jes\u00fas antes de su resurrecci\u00f3n. Ahora, despu\u00e9s de que la tumba est\u00e1 vac\u00eda y Jes\u00fas ha resucitado, el \u00e1ngel se sienta sobre la piedra que ha sido removida por su propia mano, como para enfatizar: He aqu\u00ed que me siento como garante de que el transfigurado es ahora el resucitado. Ver es creer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay muchos \u00e1ngeles de la resurrecci\u00f3n en el arte. Abren la tumba, flanquean a Jes\u00fas resucitado con las manos cruzadas en oraci\u00f3n o extienden triunfalmente un brazo con la mano extendida y el dedo \u00edndice apuntando hacia arriba, mientras que el otro brazo suele apuntar en diagonal hacia la tumba abierta. El \u00e1ngel de la resurrecci\u00f3n de Chemnitz no muestra un gesto tan dram\u00e1tico, ni de alabanza ruidosa ni de oraci\u00f3n silenciosa. Permanece tranquilamente en su pedestal, sonriendo reservadamente a quienes le miran. Mientras Nicodemo presenta los instrumentos de tortura con un gesto hablador en la p\u00e1gina del Viernes Santo, el \u00e1ngel sostiene el pa\u00f1o. Est\u00e1 tranquilamente sobre su brazo, ninguna brisa mueve su pa\u00f1o. Al igual que el \u00e1ngel, simplemente es. Eso es suficiente para autentificar la resurrecci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando la Jakobikirche de Chemnitz se convirti\u00f3 en protestante tras la Reforma, el santo sepulcro se salv\u00f3 por poco de la destrucci\u00f3n. S\u00f3lo se conserv\u00f3 por una intuici\u00f3n \u00abpedag\u00f3gica\u00bb, de la que una placa hoy desaparecida proclamaba en 1668:<br>\u00abNo la honramos, pero la toleramos y la colocamos en este digno lugar, porque predica las santas doctrinas al pueblo inculto\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante dos d\u00edas de la Edad Media, el Santo Sepulcro permanece en la iglesia en Semana Santa y cuenta la historia de la Pascua a los creyentes. El domingo de Pascua, el santuario se retira y los feligreses ven una nueva escena: Cristo resucitado sosteniendo la bandera de la cruz\/victoria y vestido con el manto rojo del gobernante. La Iglesia cat\u00f3lica ofrece otra ilustraci\u00f3n para instruir a sus fieles: El Domingo de Ramos (10 de abril), una figura de madera de Cristo recorre las calles montado en un burro, conmemorando la entrada de Jes\u00fas en Jerusal\u00e9n. El d\u00eda de la Asunci\u00f3n (15 de agosto), ya en la d\u00e9cada de 1960, una figura de Mar\u00eda en un trono es llevada por las calles de la regi\u00f3n del Ruhr en una litera, acompa\u00f1ada principalmente por mujeres y ni\u00f1os que cantan y rezan mientras esparcen flores por el camino. En Navidad, el pesebre con Jos\u00e9 y Mar\u00eda, el ni\u00f1o Jes\u00fas, el buey y el burro ilustran los acontecimientos b\u00edblicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marlen Wagner<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El \u00e1ngel de la resurrecci\u00f3n de Chemnitz no muestra ning\u00fan gesto dram\u00e1tico, ni de alabanza ruidosa ni de oraci\u00f3n silenciosa. Se encuentra tranquilamente en su pedestal, sonr\u00ede reservadamente y sostiene el sudario vac\u00edo. <\/p>\n","protected":false},"author":3,"featured_media":2369,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108,109],"tags":[],"class_list":["post-2725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-angeles-en-chemnitz-es","category-marlen-wagner-es"],"_links":{"self":[{"href":"https:\/\/entangelments.de\/es\/wp-json\/wp\/v2\/posts\/2725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entangelments.de\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entangelments.de\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entangelments.de\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/entangelments.de\/es\/wp-json\/wp\/v2\/comments?post=2725"}],"version-history":[{"count":4,"href":"https:\/\/entangelments.de\/es\/wp-json\/wp\/v2\/posts\/2725\/revisions"}],"predecessor-version":[{"id":3489,"href":"https:\/\/entangelments.de\/es\/wp-json\/wp\/v2\/posts\/2725\/revisions\/3489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entangelments.de\/es\/wp-json\/wp\/v2\/media\/2369"}],"wp:attachment":[{"href":"https:\/\/entangelments.de\/es\/wp-json\/wp\/v2\/media?parent=2725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entangelments.de\/es\/wp-json\/wp\/v2\/categories?post=2725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entangelments.de\/es\/wp-json\/wp\/v2\/tags?post=2725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}